{"id":7347,"count":1,"description":"","link":"https:\/\/intercoaching.fr\/de\/tag\/evaluation-des-plateformes\/","name":"\u00e9valuation des plateformes","slug":"evaluation-des-plateformes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/intercoaching.fr\/de\/wp-json\/wp\/v2\/tags\/7347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intercoaching.fr\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/intercoaching.fr\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/intercoaching.fr\/de\/wp-json\/wp\/v2\/posts?tags=7347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}