{"id":7349,"count":1,"description":"","link":"https:\/\/intercoaching.fr\/it\/tag\/recrutement-en-ligne\/","name":"recrutement en ligne","slug":"recrutement-en-ligne","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/intercoaching.fr\/it\/wp-json\/wp\/v2\/tags\/7349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intercoaching.fr\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/intercoaching.fr\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/intercoaching.fr\/it\/wp-json\/wp\/v2\/posts?tags=7349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}